{"id":9,"count":2,"description":"","link":"https:\/\/kristin.frings-medienservice.de\/en\/category\/cms\/","name":"CMS","slug":"cms","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CMS Archive - Der gr\u00fcne Genuss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kristin.frings-medienservice.de\/en\/category\/cms\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CMS Archive - Der gr\u00fcne Genuss\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kristin.frings-medienservice.de\/en\/category\/cms\/\" \/>\n<meta property=\"og:site_name\" content=\"Der gr\u00fcne Genuss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/kristin.frings-medienservice.de\/category\/cms\/\",\"url\":\"https:\/\/kristin.frings-medienservice.de\/category\/cms\/\",\"name\":\"CMS Archive - Der gr\u00fcne Genuss\",\"isPartOf\":{\"@id\":\"https:\/\/kristin.frings-medienservice.de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/kristin.frings-medienservice.de\/category\/cms\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kristin.frings-medienservice.de\/category\/cms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/kristin.frings-medienservice.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kristin.frings-medienservice.de\/#website\",\"url\":\"https:\/\/kristin.frings-medienservice.de\/\",\"name\":\"Der gr\u00fcne Genuss\",\"description\":\"Ihr Kleinexperte f\u00fcr gro\u00dfe Genie\u00dferfragen\",\"publisher\":{\"@id\":\"https:\/\/kristin.frings-medienservice.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kristin.frings-medienservice.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kristin.frings-medienservice.de\/#organization\",\"name\":\"Der gr\u00fcne Genuss\",\"url\":\"https:\/\/kristin.frings-medienservice.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kristin.frings-medienservice.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kristin.frings-medienservice.de\/wp-content\/uploads\/2025\/02\/cropped-Transparent-Logo.png\",\"contentUrl\":\"https:\/\/kristin.frings-medienservice.de\/wp-content\/uploads\/2025\/02\/cropped-Transparent-Logo.png\",\"width\":408,\"height\":583,\"caption\":\"Der gr\u00fcne Genuss\"},\"image\":{\"@id\":\"https:\/\/kristin.frings-medienservice.de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CMS Archive - Der gr\u00fcne Genuss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kristin.frings-medienservice.de\/en\/category\/cms\/","og_locale":"en_US","og_type":"article","og_title":"CMS Archive - Der gr\u00fcne Genuss","og_url":"https:\/\/kristin.frings-medienservice.de\/en\/category\/cms\/","og_site_name":"Der gr\u00fcne Genuss","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kristin.frings-medienservice.de\/category\/cms\/","url":"https:\/\/kristin.frings-medienservice.de\/category\/cms\/","name":"CMS Archive - Der gr\u00fcne Genuss","isPartOf":{"@id":"https:\/\/kristin.frings-medienservice.de\/#website"},"breadcrumb":{"@id":"https:\/\/kristin.frings-medienservice.de\/category\/cms\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kristin.frings-medienservice.de\/category\/cms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kristin.frings-medienservice.de\/"},{"@type":"ListItem","position":2,"name":"CMS"}]},{"@type":"WebSite","@id":"https:\/\/kristin.frings-medienservice.de\/#website","url":"https:\/\/kristin.frings-medienservice.de\/","name":"Der gr\u00fcne Genuss","description":"Ihr Kleinexperte f\u00fcr gro\u00dfe Genie\u00dferfragen","publisher":{"@id":"https:\/\/kristin.frings-medienservice.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kristin.frings-medienservice.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kristin.frings-medienservice.de\/#organization","name":"Der gr\u00fcne Genuss","url":"https:\/\/kristin.frings-medienservice.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kristin.frings-medienservice.de\/#\/schema\/logo\/image\/","url":"https:\/\/kristin.frings-medienservice.de\/wp-content\/uploads\/2025\/02\/cropped-Transparent-Logo.png","contentUrl":"https:\/\/kristin.frings-medienservice.de\/wp-content\/uploads\/2025\/02\/cropped-Transparent-Logo.png","width":408,"height":583,"caption":"Der gr\u00fcne Genuss"},"image":{"@id":"https:\/\/kristin.frings-medienservice.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kristin.frings-medienservice.de\/en\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kristin.frings-medienservice.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kristin.frings-medienservice.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kristin.frings-medienservice.de\/en\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}